{"id":218,"count":1,"description":"","link":"https:\/\/tierra-tour.com\/ru\/category\/bridesconfidential-com-hotteste-kvinner-i-verden-60\/","name":"bridesconfidential.com hotteste-kvinner-i-verden postordre brud p\u0413\u0490 ordentlig?","slug":"bridesconfidential-com-hotteste-kvinner-i-verden-60","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/tierra-tour.com\/ru\/wp-json\/wp\/v2\/categories\/218","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tierra-tour.com\/ru\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/tierra-tour.com\/ru\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/tierra-tour.com\/ru\/wp-json\/wp\/v2\/posts?categories=218"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}